{"id":89,"date":"2023-08-12T11:00:00","date_gmt":"2023-08-12T14:00:00","guid":{"rendered":"https:\/\/demosites.royal-elementor-addons.com\/personal-blog-v3\/?p=89"},"modified":"2024-07-10T15:37:44","modified_gmt":"2024-07-10T18:37:44","slug":"setting-goals-and-staying-motivated","status":"publish","type":"post","link":"https:\/\/liartecontemporanea.com\/index.php\/2023\/08\/12\/setting-goals-and-staying-motivated\/","title":{"rendered":"9 exposi\u00e7\u00f5es para n\u00e3o deixar de ir no m\u00eas de agosto em S\u00e3o Paulo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"89\" class=\"elementor elementor-89\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c3b7e38 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2c3b7e38\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41f428f4\" data-id=\"41f428f4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69903f3 elementor-widget elementor-widget-text-editor\" data-id=\"69903f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>MASP, MIS, MAM e Pinacoteca est\u00e3o recheados de novas exposi\u00e7\u00f5es que integram o calend\u00e1rio cultural da cidade neste m\u00eas de agosto<\/p>\n<p>Originalmente publicado em: https:\/\/casacor.abril.com.br\/arte\/exposicoes-nao-deixar-de-ir-agosto-2023\/amp\/<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a7bc327 elementor-widget elementor-widget-text-editor\" data-id=\"7a7bc327\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O m\u00eas de agosto est\u00e1 com uma <strong>programa\u00e7\u00e3o cultural<\/strong><strong>recheada<\/strong> na cidade de S\u00e3o Paulo! Diversas exposi\u00e7\u00f5es j\u00e1 desembarcaram no <strong>calend\u00e1rio cultural<\/strong> da capital, entre elas, destaque para \u201c<strong>Realidades e Simulacros<\/strong>\u201c, no MAM e a exposi\u00e7\u00e3o in\u00e9dita do \u201c<strong>B.B. King: um mundo melhor em algum lugar<\/strong>\u201c, no MIS.<\/p>\n<p>A seguir, listamos <strong>9\u00a0exposi\u00e7\u00f5es<\/strong> que voc\u00ea n\u00e3o pode deixar de conferir neste m\u00eas de agosto na capital paulista!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e4e76ab elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"e4e76ab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-12e3641\" data-id=\"12e3641\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa2aee0 elementor-widget elementor-widget-heading\" data-id=\"aa2aee0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">1. Sheroanawe Hakihiiwe: tudo isso somos n\u00f3s \u2013 MASP<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f82c3f3 elementor-widget elementor-widget-image\" data-id=\"f82c3f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/1jIZUOWm3Ff85oOGZEqk-4viHQEtRipGr3AvZcTFq.jpg-240x300.webp\" class=\"attachment-medium size-medium wp-image-1030\" alt=\"\" srcset=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/1jIZUOWm3Ff85oOGZEqk-4viHQEtRipGr3AvZcTFq.jpg-240x300.webp 240w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/1jIZUOWm3Ff85oOGZEqk-4viHQEtRipGr3AvZcTFq.jpg-819x1024.webp 819w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/1jIZUOWm3Ff85oOGZEqk-4viHQEtRipGr3AvZcTFq.jpg-768x960.webp 768w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/1jIZUOWm3Ff85oOGZEqk-4viHQEtRipGr3AvZcTFq.jpg-1229x1536.webp 1229w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/1jIZUOWm3Ff85oOGZEqk-4viHQEtRipGr3AvZcTFq.jpg-1639x2048.webp 1639w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77fd27e elementor-widget elementor-widget-text-editor\" data-id=\"77fd27e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Sheroanawe Hakihiiwe<\/strong> (Sheroana, Venezuela, 1971) \u00e9 um <strong>artista\u00a0<\/strong><b>Yanomami<\/b>\u00a0que, desde a d\u00e9cada de 1990, produz desenhos, monotipos e pinturas. Sua linguagem art\u00edstica delicada, abstrata e m\u00ednima usa linhas retas e curvas org\u00e2nicas, pontos, c\u00edrculos, tri\u00e2ngulos, zigue-zagues, arcos e cruzes. Assim, a mostra de <strong>Sheroanawe Hakihiiwe<\/strong> integra o ano de programa\u00e7\u00e3o do MASP dedicado \u00e0s <strong>hist\u00f3rias ind\u00edgenas<\/strong>.<\/p>\n<p><span class=\"amp-wp-b02d618\" data-amp-original-style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif\">Com <strong>48 trabalhos<\/strong>, esta mostra leva o subt\u00edtulo <strong>Ihi hei komi thepe kamie yamaki<\/strong> [Tudo isso somos n\u00f3s], sugerido por Hakihiiwe para incorporar a <strong>diversidade de elementos<\/strong> que formam sua comunidade e seu entorno. \u201cTudo isso somos n\u00f3s\u201d, para o artista, significa \u201ctudo aquilo que <strong>est\u00e1 ali na selva.<\/strong>Vivemos todos l\u00e1, e n\u00e3o \u00e9 s\u00f3 n\u00f3s. L\u00e1 tem grandes rios, grandes lagoas, os animais, todos os insetos. Vou resgatando tudo que est\u00e1 l\u00e1 onde vivo\u201d.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2ed6cfd elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2ed6cfd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1b435de\" data-id=\"1b435de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1751d9a elementor-widget elementor-widget-heading\" data-id=\"1751d9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">2. Realidades e Simulacros \u2013 MAM<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33195fa elementor-widget elementor-widget-image\" data-id=\"33195fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1746\" src=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/MamRealidades_Vista-da-obra-de-Fernando-Velazquez-Gorgona-01-serie-Outras-Naturezas_2023.-Foto-Luis-Felipe-Abbud.jpg-scaled.webp\" class=\"attachment-full size-full wp-image-1035\" alt=\"\" srcset=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/MamRealidades_Vista-da-obra-de-Fernando-Velazquez-Gorgona-01-serie-Outras-Naturezas_2023.-Foto-Luis-Felipe-Abbud.jpg-scaled.webp 2560w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/MamRealidades_Vista-da-obra-de-Fernando-Velazquez-Gorgona-01-serie-Outras-Naturezas_2023.-Foto-Luis-Felipe-Abbud.jpg-300x205.webp 300w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/MamRealidades_Vista-da-obra-de-Fernando-Velazquez-Gorgona-01-serie-Outras-Naturezas_2023.-Foto-Luis-Felipe-Abbud.jpg-1024x699.webp 1024w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/MamRealidades_Vista-da-obra-de-Fernando-Velazquez-Gorgona-01-serie-Outras-Naturezas_2023.-Foto-Luis-Felipe-Abbud.jpg-768x524.webp 768w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/MamRealidades_Vista-da-obra-de-Fernando-Velazquez-Gorgona-01-serie-Outras-Naturezas_2023.-Foto-Luis-Felipe-Abbud.jpg-1536x1048.webp 1536w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/MamRealidades_Vista-da-obra-de-Fernando-Velazquez-Gorgona-01-serie-Outras-Naturezas_2023.-Foto-Luis-Felipe-Abbud.jpg-2048x1397.webp 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f223b62 elementor-widget elementor-widget-text-editor\" data-id=\"f223b62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>At\u00e9 17 de dezembro, o <b>Museu de Arte Moderna de S\u00e3o Paulo (MAM)\u00a0<\/b>convida seus visitantes a <span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">perceber a realidade de outra maneira e interagir com outras dimens\u00f5es atrav\u00e9s da nova exposi\u00e7\u00e3o \u201c<\/span><b>Realidades e Simulacros<\/b>\u201c, <span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">que <\/span><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">apresenta obras in\u00e9ditas em realidade aumentada no <\/span><b>Jardim de Esculturas<\/b><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\"> e em diferentes pontos do <\/span><b>Parque Ibirapuera<\/b>, em S\u00e3o Paulo.<\/p>\n<p><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">Com curadoria de <\/span><b>Marcus Bastos<\/b><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">, artista e pesquisador na converg\u00eancia entre audiovisual, arte e novas m\u00eddias, e de <\/span><b>Cau\u00ea Alves<\/b><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">, curador-chefe do MAM, a exposi\u00e7\u00e3o re\u00fane obras do <\/span><b>Coletivo Coletores<\/b><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">, <\/span><b>Daniel Lima<\/b><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">, <\/span><b>Dudu Tsuda<\/b><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">, <\/span><b>Eder Santos<\/b><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">, <\/span><b>Fernando Velazquez,<\/b> <b>Giselle Beiguelman<\/b><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">, <\/span><b>Katia Maciel<\/b><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">, <\/span><b>Lucas Bambozzi<\/b><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">, <\/span><b>Regina Silveira<\/b><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\"> e <\/span><b>Paola Barreto<\/b><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">. Cada artista recebeu um convite da curadoria para criar experi\u00eancias digitais, obras virtuais em realidade aumentada que integram o jogo de multiplicidades que \u00e9 a exposi\u00e7\u00e3o.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c122aba elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"c122aba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c7c2f33\" data-id=\"c7c2f33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3ab7c5 elementor-widget elementor-widget-heading\" data-id=\"a3ab7c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">3. EL\u00c3, por Hanz Ronald \u2013 Galeria Plexi<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84449dd elementor-widget elementor-widget-image\" data-id=\"84449dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"696\" src=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/Amores-de-verao-parte-1-2023-Hanz-Ronald-Galeria-Plexi-Credito-Pamela-Lahaud-.jpg-1024x742.webp\" class=\"attachment-large size-large wp-image-1032\" alt=\"\" srcset=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/Amores-de-verao-parte-1-2023-Hanz-Ronald-Galeria-Plexi-Credito-Pamela-Lahaud-.jpg-1024x742.webp 1024w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/Amores-de-verao-parte-1-2023-Hanz-Ronald-Galeria-Plexi-Credito-Pamela-Lahaud-.jpg-300x217.webp 300w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/Amores-de-verao-parte-1-2023-Hanz-Ronald-Galeria-Plexi-Credito-Pamela-Lahaud-.jpg-768x556.webp 768w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/Amores-de-verao-parte-1-2023-Hanz-Ronald-Galeria-Plexi-Credito-Pamela-Lahaud-.jpg-1536x1113.webp 1536w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/Amores-de-verao-parte-1-2023-Hanz-Ronald-Galeria-Plexi-Credito-Pamela-Lahaud-.jpg-2048x1484.webp 2048w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2a3323 elementor-widget elementor-widget-text-editor\" data-id=\"b2a3323\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A partir de <strong>24 de agosto<\/strong>, o <span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">p\u00fablico poder\u00e1 conferir de perto os trabalhos da jovem artista <strong>Hanz Ronald<\/strong>, de apenas 27 anos, que busca relacion<\/span><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">ar<strong> elementos figurativos<\/strong> com<strong> abstratos<\/strong>. A mostra<\/span><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">\u00a0\u201c<\/span><i class=\"amp-wp-e230648\" data-amp-original-style=\"text-align: justify;font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif\">EL\u00c3\u201d,<\/i><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">\u00a0na <\/span><b class=\"amp-wp-e230648\" data-amp-original-style=\"text-align: justify;font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif\">Galeria Plexi<\/b>, <span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">exibe dez obras in\u00e9ditas, entre pinturas e desenhos, que partem de um olhar <strong>pessoal<\/strong> e<strong>\u00edntimo<\/strong> sobre os desejos e inquietudes do artista.\u00a0<\/span><\/p>\n<p><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">Destaque para a obra <\/span><i><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\">O toque de tudo e todas as coisas<\/span><\/i><span class=\"amp-wp-668e0a1\" data-amp-original-style=\"font-weight: 400\"> (2023), que Hanz utiliza<strong> massas de cor<\/strong> e sobreposi\u00e7\u00f5es de formas, fazendo com que <strong>corpos fragmentados<\/strong> se conectem por pinceladas<strong> expressivas<\/strong> e <strong>abstratas<\/strong> de um l\u00edquido.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-59f44f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"59f44f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-205d584\" data-id=\"205d584\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e61369f elementor-widget elementor-widget-heading\" data-id=\"e61369f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">4. B.B. King: um mundo melhor em algum lugar \u2013 MIS<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a50d016 elementor-widget elementor-widget-image\" data-id=\"a50d016\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"451\" src=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/ogOMrdv3KHElsL8Uzmn6WlVczh0AUOnIkJdQ7YiM.jpeg-1024x481.webp\" class=\"attachment-large size-large wp-image-1036\" alt=\"\" srcset=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/ogOMrdv3KHElsL8Uzmn6WlVczh0AUOnIkJdQ7YiM.jpeg-1024x481.webp 1024w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/ogOMrdv3KHElsL8Uzmn6WlVczh0AUOnIkJdQ7YiM.jpeg-300x141.webp 300w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/ogOMrdv3KHElsL8Uzmn6WlVczh0AUOnIkJdQ7YiM.jpeg-768x361.webp 768w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/ogOMrdv3KHElsL8Uzmn6WlVczh0AUOnIkJdQ7YiM.jpeg-1536x721.webp 1536w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/ogOMrdv3KHElsL8Uzmn6WlVczh0AUOnIkJdQ7YiM.jpeg-2048x962.webp 2048w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3de7ce elementor-widget elementor-widget-text-editor\" data-id=\"d3de7ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>At\u00e9 outubro, diversos itens da vida e obra de<strong> B.B. King<\/strong> estar\u00e3o dispon\u00edveis para visita\u00e7\u00e3o do p\u00fablico em uma exposi\u00e7\u00e3o in\u00e9dita no <strong>MIS<\/strong> dedicada ao<strong> Rei do Blues<\/strong>. A mostra\u00a0\u201c<strong>B.B. King: um mundo melhor em algum lugar<\/strong>\u201d\u00a0pega emprestado parte do nome do disco de <strong>1981<\/strong> para tratar de temas de segrega\u00e7\u00e3o e inclus\u00e3o, proporcionando uma <strong>experi\u00eancia sensorial<\/strong>.<\/p>\n<p>Primeira exposi\u00e7\u00e3o inteiramente dedicada ao artista no Brasil, o projeto traz <strong>itens hist\u00f3ricos<\/strong> da vida de B.B. King. Entre os destaques, est\u00e3o imagens do acervo do B.B. King Museum, de <strong>diversas fases da carreira<\/strong> do artista, desde o jovem <strong>Riley Ben King<\/strong>, aos 23 anos, com o viol\u00e3o Gibson L48, de Michael Ocs, at\u00e9 seu\u202fretrato exibindo o\u202fpr\u00eamio de Melhor \u00c1lbum de Blues Tradicional na <strong>42\u00aa Cerim\u00f4nia do Grammy, em 2000<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-253c4ce elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"253c4ce\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-62d6145\" data-id=\"62d6145\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-981cbb7 elementor-widget elementor-widget-heading\" data-id=\"981cbb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">5. Masterchef \u2013 Imers\u00e3o &amp; Sentidos \u2013 Shopping Vila Ol\u00edmpia<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63c8776 elementor-widget elementor-widget-image\" data-id=\"63c8776\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"840\" height=\"472\" src=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/72691_w840h0_1691525989masterchef-imersao-sentidos-01-divulgacao.png.webp\" class=\"attachment-large size-large wp-image-1031\" alt=\"\" srcset=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/72691_w840h0_1691525989masterchef-imersao-sentidos-01-divulgacao.png.webp 840w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/72691_w840h0_1691525989masterchef-imersao-sentidos-01-divulgacao.png-300x169.webp 300w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/72691_w840h0_1691525989masterchef-imersao-sentidos-01-divulgacao.png-768x432.webp 768w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dddbdb8 elementor-widget elementor-widget-text-editor\" data-id=\"dddbdb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A partir de <strong>20 de agosto<\/strong>, a imagina\u00e7\u00e3o dos f\u00e3s do <em>reality<\/em>culin\u00e1rio mais assistido do mundo, o<strong> Masterchef<\/strong>, poder\u00e3o contar com a <strong>exposi\u00e7\u00e3o imersiva<\/strong> do <em>reality<\/em> no<strong> Shopping Vila Ol\u00edmpia<\/strong>. A partir de experi\u00eancias tecnol\u00f3gicas <strong>imersivas<\/strong>e<strong> sensoriais<\/strong>, a mostra explora os <strong>cinco sentidos<\/strong> com os mesmos sabores, aromas, sons, texturas e elementos visuais do est\u00fadio comandado por Ana Paula Padr\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-34ed82c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"34ed82c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ee02f81\" data-id=\"ee02f81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c9bae4 elementor-widget elementor-widget-heading\" data-id=\"3c9bae4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">6. Jap\u00e3o em miniaturas, por Tatsuya Tanaka \u2013 Japan House<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a68a610 elementor-widget elementor-widget-image\" data-id=\"a68a610\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/Japao-em-Miniaturas-Marina-Melchers-29-.jpg-1024x683.webp\" class=\"attachment-large size-large wp-image-1034\" alt=\"\" srcset=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/Japao-em-Miniaturas-Marina-Melchers-29-.jpg-1024x683.webp 1024w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/Japao-em-Miniaturas-Marina-Melchers-29-.jpg-300x200.webp 300w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/Japao-em-Miniaturas-Marina-Melchers-29-.jpg-768x512.webp 768w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/Japao-em-Miniaturas-Marina-Melchers-29-.jpg.webp 1150w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b8b7c2 elementor-widget elementor-widget-text-editor\" data-id=\"7b8b7c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cenas do cotidiano, da paisagem e das tradi\u00e7\u00f5es japonesas ganham vida no formato de <strong>miniaturas<\/strong> atrav\u00e9s pelas m\u00e3os do artista e fot\u00f3grafo japon\u00eas <strong><a href=\"https:\/\/casacor.abril.com.br\/arte\/vida-em-miniatura-tatsuya-tanaka\/\">Tatsuya Tanaka<\/a><\/strong>. Seu trabalho, que ilustra o conceito \u201c<em>mitate<\/em>\u201d \u2013 na qual a arte em miniatura \u00e9 fotografada com a tem\u00e1tica de bonecos de diorama e coisas do dia a dia \u2013, est\u00e1 em exibi\u00e7\u00e3o na <a href=\"https:\/\/casacor.abril.com.br\/tudo-sobre\/japan-house\/\">Japan House S\u00e3o Paulo<\/a> at\u00e9 o dia 08 de outubro de 2023, com entrada gratuita.<\/p>\n<p>Ao todo, as <strong>37 obras<\/strong> foram criadas a partir de elementos como conchas, alimentos como macarr\u00e3o e sushi, itens de maquiagem, canudos, pregadores, leques, entre outros <strong>objetos do dia a dia japon\u00eas<\/strong>; que estar\u00e3o divididas em cinco grupos principais: esta\u00e7\u00f5es do ano e seus eventos, cenas do Jap\u00e3o tradicional, cenas do Jap\u00e3o moderno, vida cotidiana e pr\u00e1ticas tradicionais.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3fa28fb elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3fa28fb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c15ee8b\" data-id=\"c15ee8b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04e3187 elementor-widget elementor-widget-heading\" data-id=\"04e3187\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">7. \u201cSolastalgia\u201d \u2013 MAC USP<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ae34be elementor-widget elementor-widget-image\" data-id=\"4ae34be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"902\" height=\"618\" src=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/image003.png.webp\" class=\"attachment-large size-large wp-image-1033\" alt=\"\" srcset=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/image003.png.webp 902w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/image003.png-300x206.webp 300w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/image003.png-768x526.webp 768w\" sizes=\"(max-width: 902px) 100vw, 902px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c7b1b0 elementor-widget elementor-widget-text-editor\" data-id=\"2c7b1b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O conceito de <strong>solastalgia<\/strong> \u2013 estresse mental e\/ou existencial causado por mudan\u00e7as ambientais abruptas, n\u00e3o s\u00f3 por consequ\u00eancias naturais, mas tamb\u00e9m por modelos de extrativismo danosos \u2013 norteia e intitula a <strong>exposi\u00e7\u00e3o in\u00e9dita<\/strong>que o cineasta, artista visual e pesquisador em novas m\u00eddias, <strong>Lucas Bambozzi<\/strong>, exibe at\u00e9 1\u00ba de outubro no <strong>MAC \u2013 Museu de Arte Contempor\u00e2nea da Universidade de S\u00e3o Paulo<\/strong>.<\/p>\n<p>A mostra, com curadoria assinada por <strong>Fernanda Pitta<\/strong>, traz <strong>quatro<\/strong> <strong>videoinstala\u00e7\u00f5es<\/strong> que servem como uma esp\u00e9cie de convite para o p\u00fablico refletir sobre o impacto social e ambiental das atividades mineradoras no Brasil.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-12cbb9c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"12cbb9c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-70791aa\" data-id=\"70791aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56b7c10 elementor-widget elementor-widget-heading\" data-id=\"56b7c10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">8. Iole de Freitas \u2014 IMS<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b14818c elementor-widget elementor-widget-image\" data-id=\"b14818c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"623\" src=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/unnamed-58.jpg.webp\" class=\"attachment-large size-large wp-image-1038\" alt=\"\" srcset=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/unnamed-58.jpg.webp 800w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/unnamed-58.jpg-300x234.webp 300w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/unnamed-58.jpg-768x598.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc479e0 elementor-widget elementor-widget-text-editor\" data-id=\"dc479e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A mostra que fica at\u00e9 <strong>24 de setembro<\/strong> re\u00fane fotos e filmes dos tempos em que a artista <strong>Iole de Freitas<\/strong> viveu em Mil\u00e3o, Londres e Nova York. Pouco conhecidas pelo p\u00fablico brasileiro, as obras tamb\u00e9m abordam temas como o <strong>movimento<\/strong> e a <strong>passagem do tempo<\/strong>.<\/p>\n<p>Ao reunir a produ\u00e7\u00e3o de Iole da <strong>d\u00e9cada de 1970<\/strong>, a exposi\u00e7\u00e3o evidencia a pot\u00eancia dessas obras da artista que, vistas sob a luz dos debates contempor\u00e2neos, continuam suscitando novas quest\u00f5es e perspectivas.<\/p>\n<p>Ao visitar a exposi\u00e7\u00e3o, o p\u00fablico poder\u00e1 conhecer um <strong>per\u00edodo<\/strong><strong>central<\/strong> na trajet\u00f3ria da artista, no qual ela come\u00e7a a explorar temas como o <strong>movimento<\/strong> e a <strong>transpar\u00eancia<\/strong>, que viriam marcar toda a sua obra posterior.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b108507 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"b108507\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f7c24c7\" data-id=\"f7c24c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94db303 elementor-widget elementor-widget-heading\" data-id=\"94db303\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">9. \u201cMarta Minuj\u00edn: Ao vivo\u201d \u2013 Pinacoteca<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc4bed3 elementor-widget elementor-widget-image\" data-id=\"fc4bed3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/Pinacoteca_Marta-Minujin_obras5-1024x683-1.jpg.webp\" class=\"attachment-large size-large wp-image-1037\" alt=\"\" srcset=\"https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/Pinacoteca_Marta-Minujin_obras5-1024x683-1.jpg.webp 1024w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/Pinacoteca_Marta-Minujin_obras5-1024x683-1.jpg-300x200.webp 300w, https:\/\/liartecontemporanea.com\/wp-content\/uploads\/2023\/04\/Pinacoteca_Marta-Minujin_obras5-1024x683-1.jpg-768x512.webp 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-459aec1 elementor-widget elementor-widget-text-editor\" data-id=\"459aec1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A exposi\u00e7\u00e3o \u201c<strong>Marta Minuj\u00edn: Ao vivo<\/strong>\u201d \u00e9 a primeira mostra panor\u00e2mica no Brasil de uma das artistas latino-americanas mais relevantes da sua gera\u00e7\u00e3o. Exposta na <a href=\"https:\/\/casacor.abril.com.br\/tudo-sobre\/pinacoteca-de-sao-paulo\/\">Pinacoteca de S\u00e3o Paulo<\/a>, a mostra articula mais de 100 obras da argentina<strong> Marta Minuj\u00edn<\/strong>, que transita entre diversas linguagens, escalas, circuitos art\u00edsticos e sociais.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>MASP, MIS, MAM e Pinacoteca est\u00e3o recheados de novas exposi\u00e7\u00f5es que integram o calend\u00e1rio cultural da cidade neste m\u00eas de agosto Originalmente publicado em: https:\/\/casacor.abril.com.br\/arte\/exposicoes-nao-deixar-de-ir-agosto-2023\/amp\/ O m\u00eas de agosto est\u00e1 com uma programa\u00e7\u00e3o culturalrecheada na cidade de S\u00e3o Paulo! Diversas exposi\u00e7\u00f5es j\u00e1 desembarcaram no calend\u00e1rio cultural da capital, entre elas, destaque para \u201cRealidades e Simulacros\u201c, no MAM e a exposi\u00e7\u00e3o in\u00e9dita do \u201cB.B. King: um mundo melhor em algum lugar\u201c, no MIS. A seguir, listamos 9\u00a0exposi\u00e7\u00f5es que voc\u00ea n\u00e3o pode deixar de conferir neste m\u00eas de agosto na capital paulista! 1. Sheroanawe Hakihiiwe: tudo isso somos n\u00f3s \u2013 MASP Sheroanawe Hakihiiwe (Sheroana, Venezuela, 1971) \u00e9 um artista\u00a0Yanomami\u00a0que, desde a d\u00e9cada de 1990, produz desenhos, monotipos e pinturas. Sua linguagem art\u00edstica delicada, abstrata e m\u00ednima usa linhas retas e curvas org\u00e2nicas, pontos, c\u00edrculos, tri\u00e2ngulos, zigue-zagues, arcos e cruzes. Assim, a mostra de Sheroanawe Hakihiiwe integra o ano de programa\u00e7\u00e3o do MASP dedicado \u00e0s hist\u00f3rias ind\u00edgenas. Com 48 trabalhos, esta mostra leva o subt\u00edtulo Ihi hei komi thepe kamie yamaki [Tudo isso somos n\u00f3s], sugerido por Hakihiiwe para incorporar a diversidade de elementos que formam sua comunidade e seu entorno. \u201cTudo isso somos n\u00f3s\u201d, para o artista, significa \u201ctudo aquilo que est\u00e1 ali na selva.Vivemos todos l\u00e1, e n\u00e3o \u00e9 s\u00f3 n\u00f3s. L\u00e1 tem grandes rios, grandes lagoas, os animais, todos os insetos. Vou resgatando tudo que est\u00e1 l\u00e1 onde vivo\u201d. 2. Realidades e Simulacros \u2013 MAM At\u00e9 17 de dezembro, o Museu de Arte Moderna de S\u00e3o Paulo (MAM)\u00a0convida seus visitantes a perceber a realidade de outra maneira e interagir com outras dimens\u00f5es atrav\u00e9s da nova exposi\u00e7\u00e3o \u201cRealidades e Simulacros\u201c, que apresenta obras in\u00e9ditas em realidade aumentada no Jardim de Esculturas e em diferentes pontos do Parque Ibirapuera, em S\u00e3o Paulo. Com curadoria de Marcus Bastos, artista e pesquisador na converg\u00eancia entre audiovisual, arte e novas m\u00eddias, e de Cau\u00ea Alves, curador-chefe do MAM, a exposi\u00e7\u00e3o re\u00fane obras do Coletivo Coletores, Daniel Lima, Dudu Tsuda, Eder Santos, Fernando Velazquez, Giselle Beiguelman, Katia Maciel, Lucas Bambozzi, Regina Silveira e Paola Barreto. Cada artista recebeu um convite da curadoria para criar experi\u00eancias digitais, obras virtuais em realidade aumentada que integram o jogo de multiplicidades que \u00e9 a exposi\u00e7\u00e3o. 3. EL\u00c3, por Hanz Ronald \u2013 Galeria Plexi A partir de 24 de agosto, o p\u00fablico poder\u00e1 conferir de perto os trabalhos da jovem artista Hanz Ronald, de apenas 27 anos, que busca relacionar elementos figurativos com abstratos. A mostra\u00a0\u201cEL\u00c3\u201d,\u00a0na Galeria Plexi, exibe dez obras in\u00e9ditas, entre pinturas e desenhos, que partem de um olhar pessoal e\u00edntimo sobre os desejos e inquietudes do artista. Destaque para a obra O toque de tudo e todas as coisas (2023), que Hanz utiliza massas de cor e sobreposi\u00e7\u00f5es de formas, fazendo com que corpos fragmentados se conectem por pinceladas expressivas e abstratas de um l\u00edquido. 4. B.B. King: um mundo melhor em algum lugar \u2013 MIS At\u00e9 outubro, diversos itens da vida e obra de B.B. King estar\u00e3o dispon\u00edveis para visita\u00e7\u00e3o do p\u00fablico em uma exposi\u00e7\u00e3o in\u00e9dita no MIS dedicada ao Rei do Blues. A mostra\u00a0\u201cB.B. King: um mundo melhor em algum lugar\u201d\u00a0pega emprestado parte do nome do disco de 1981 para tratar de temas de segrega\u00e7\u00e3o e inclus\u00e3o, proporcionando uma experi\u00eancia sensorial. Primeira exposi\u00e7\u00e3o inteiramente dedicada ao artista no Brasil, o projeto traz itens hist\u00f3ricos da vida de B.B. King. Entre os destaques, est\u00e3o imagens do acervo do B.B. King Museum, de diversas fases da carreira do artista, desde o jovem Riley Ben King, aos 23 anos, com o viol\u00e3o Gibson L48, de Michael Ocs, at\u00e9 seu\u202fretrato exibindo o\u202fpr\u00eamio de Melhor \u00c1lbum de Blues Tradicional na 42\u00aa Cerim\u00f4nia do Grammy, em 2000. 5. Masterchef \u2013 Imers\u00e3o &#038; Sentidos \u2013 Shopping Vila Ol\u00edmpia A partir de 20 de agosto, a imagina\u00e7\u00e3o dos f\u00e3s do realityculin\u00e1rio mais assistido do mundo, o Masterchef, poder\u00e3o contar com a exposi\u00e7\u00e3o imersiva do reality no Shopping Vila Ol\u00edmpia. A partir de experi\u00eancias tecnol\u00f3gicas imersivase sensoriais, a mostra explora os cinco sentidos com os mesmos sabores, aromas, sons, texturas e elementos visuais do est\u00fadio comandado por Ana Paula Padr\u00e3o. 6. Jap\u00e3o em miniaturas, por Tatsuya Tanaka \u2013 Japan House Cenas do cotidiano, da paisagem e das tradi\u00e7\u00f5es japonesas ganham vida no formato de miniaturas atrav\u00e9s pelas m\u00e3os do artista e fot\u00f3grafo japon\u00eas Tatsuya Tanaka. Seu trabalho, que ilustra o conceito \u201cmitate\u201d \u2013 na qual a arte em miniatura \u00e9 fotografada com a tem\u00e1tica de bonecos de diorama e coisas do dia a dia \u2013, est\u00e1 em exibi\u00e7\u00e3o na Japan House S\u00e3o Paulo at\u00e9 o dia 08 de outubro de 2023, com entrada gratuita. Ao todo, as 37 obras foram criadas a partir de elementos como conchas, alimentos como macarr\u00e3o e sushi, itens de maquiagem, canudos, pregadores, leques, entre outros objetos do dia a dia japon\u00eas; que estar\u00e3o divididas em cinco grupos principais: esta\u00e7\u00f5es do ano e seus eventos, cenas do Jap\u00e3o tradicional, cenas do Jap\u00e3o moderno, vida cotidiana e pr\u00e1ticas tradicionais. 7. \u201cSolastalgia\u201d \u2013 MAC USP O conceito de solastalgia \u2013 estresse mental e\/ou existencial causado por mudan\u00e7as ambientais abruptas, n\u00e3o s\u00f3 por consequ\u00eancias naturais, mas tamb\u00e9m por modelos de extrativismo danosos \u2013 norteia e intitula a exposi\u00e7\u00e3o in\u00e9ditaque o cineasta, artista visual e pesquisador em novas m\u00eddias, Lucas Bambozzi, exibe at\u00e9 1\u00ba de outubro no MAC \u2013 Museu de Arte Contempor\u00e2nea da Universidade de S\u00e3o Paulo. A mostra, com curadoria assinada por Fernanda Pitta, traz quatro videoinstala\u00e7\u00f5es que servem como uma esp\u00e9cie de convite para o p\u00fablico refletir sobre o impacto social e ambiental das atividades mineradoras no Brasil. 8. Iole de Freitas \u2014 IMS A mostra que fica at\u00e9 24 de setembro re\u00fane fotos e filmes dos tempos em que a artista Iole de Freitas viveu em Mil\u00e3o, Londres e Nova York. Pouco conhecidas pelo p\u00fablico brasileiro, as obras tamb\u00e9m abordam temas como o movimento e a passagem do tempo. Ao reunir a produ\u00e7\u00e3o de Iole da d\u00e9cada de 1970, a exposi\u00e7\u00e3o evidencia a pot\u00eancia dessas obras da artista que, vistas sob a luz dos debates contempor\u00e2neos, continuam suscitando novas quest\u00f5es<\/p>\n","protected":false},"author":2,"featured_media":1025,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[31],"tags":[29,33,32],"class_list":["post-89","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exposicoes","tag-artista","tag-sao-paulo","tag-viagem"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/liartecontemporanea.com\/index.php\/wp-json\/wp\/v2\/posts\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liartecontemporanea.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/liartecontemporanea.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/liartecontemporanea.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/liartecontemporanea.com\/index.php\/wp-json\/wp\/v2\/comments?post=89"}],"version-history":[{"count":7,"href":"https:\/\/liartecontemporanea.com\/index.php\/wp-json\/wp\/v2\/posts\/89\/revisions"}],"predecessor-version":[{"id":1073,"href":"https:\/\/liartecontemporanea.com\/index.php\/wp-json\/wp\/v2\/posts\/89\/revisions\/1073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/liartecontemporanea.com\/index.php\/wp-json\/wp\/v2\/media\/1025"}],"wp:attachment":[{"href":"https:\/\/liartecontemporanea.com\/index.php\/wp-json\/wp\/v2\/media?parent=89"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/liartecontemporanea.com\/index.php\/wp-json\/wp\/v2\/categories?post=89"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/liartecontemporanea.com\/index.php\/wp-json\/wp\/v2\/tags?post=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}